{"id":366,"date":"2022-12-06T12:15:09","date_gmt":"2022-12-06T11:15:09","guid":{"rendered":"https:\/\/huisartsenspoedpost-zeist.mindd.dev\/?p=366"},"modified":"2022-12-06T12:15:11","modified_gmt":"2022-12-06T11:15:11","slug":"nivel-zorgregistratie","status":"publish","type":"post","link":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/","title":{"rendered":"Nivel zorgregistratie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Huisartsenposten Amsterdam doet mee aan landelijke tellingen van Nivel Zorgregistraties eerste lijn. Het Nivel gebruikt de tellingen om vraagstukken binnen de gezondheidszorg in Nederland te beantwoorden. Zo draagt u bij aan belangrijk wetenschappelijk onderzoek. Het Nivel houdt zich hierbij strikt aan de AVG (Algemene Verordening Gegevensbescherming). Liever niet meedoen met de tellingen? Meld dit bij uw zorgverlener.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Huisartsenposten Amsterdam doet mee aan landelijke tellingen van Nivel Zorgregistraties eerste lijn. Het Nivel gebruikt de tellingen om vraagstukken binnen de gezondheidszorg in Nederland te beantwoorden. Zo draagt u bij aan belangrijk wetenschappelijk onderzoek. Het Nivel houdt zich hierbij strikt aan de AVG (Algemene Verordening Gegevensbescherming). Liever niet meedoen met de tellingen? Meld dit bij [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1],"class_list":["post-366","post","type-post","status-publish","format-standard","hentry","category-geen-onderdeel-van-een-categorie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nivel zorgregistratie - Huisartsenpost Drechtdokters - English<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nivel zorgregistratie - Huisartsenpost Drechtdokters - English\" \/>\n<meta property=\"og:description\" content=\"Huisartsenposten Amsterdam doet mee aan landelijke tellingen van Nivel Zorgregistraties eerste lijn. Het Nivel gebruikt de tellingen om vraagstukken binnen de gezondheidszorg in Nederland te beantwoorden. Zo draagt u bij aan belangrijk wetenschappelijk onderzoek. Het Nivel houdt zich hierbij strikt aan de AVG (Algemene Verordening Gegevensbescherming). Liever niet meedoen met de tellingen? Meld dit bij [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/\" \/>\n<meta property=\"og:site_name\" content=\"Huisartsenpost Drechtdokters - English\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-06T11:15:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-06T11:15:11+00:00\" \/>\n<meta name=\"author\" content=\"MINDD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MINDD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/\"},\"author\":{\"name\":\"MINDD\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/#\\\/schema\\\/person\\\/a9e28e081516b814b3224fb1c8f07206\"},\"headline\":\"Nivel zorgregistratie\",\"datePublished\":\"2022-12-06T11:15:09+00:00\",\"dateModified\":\"2022-12-06T11:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/\"},\"wordCount\":59,\"commentCount\":0,\"articleSection\":[\"Geen onderdeel van een categorie\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/\",\"url\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/\",\"name\":\"Nivel zorgregistratie - Huisartsenpost Drechtdokters - English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/#website\"},\"datePublished\":\"2022-12-06T11:15:09+00:00\",\"dateModified\":\"2022-12-06T11:15:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/#\\\/schema\\\/person\\\/a9e28e081516b814b3224fb1c8f07206\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/2022\\\/12\\\/06\\\/nivel-zorgregistratie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nivel zorgregistratie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/\",\"name\":\"Huisartsenpost Drechtdokters - English\",\"description\":\"Development site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/#\\\/schema\\\/person\\\/a9e28e081516b814b3224fb1c8f07206\",\"name\":\"MINDD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/wp-content\\\/litespeed\\\/avatar\\\/74\\\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512\",\"url\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/wp-content\\\/litespeed\\\/avatar\\\/74\\\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512\",\"contentUrl\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/wp-content\\\/litespeed\\\/avatar\\\/74\\\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512\",\"caption\":\"MINDD\"},\"url\":\"https:\\\/\\\/huisartsenpostdrechtdokters.nl\\\/en\\\/blog\\\/author\\\/mindd-beheer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nivel zorgregistratie - Huisartsenpost Drechtdokters - English","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/","og_locale":"en_US","og_type":"article","og_title":"Nivel zorgregistratie - Huisartsenpost Drechtdokters - English","og_description":"Huisartsenposten Amsterdam doet mee aan landelijke tellingen van Nivel Zorgregistraties eerste lijn. Het Nivel gebruikt de tellingen om vraagstukken binnen de gezondheidszorg in Nederland te beantwoorden. Zo draagt u bij aan belangrijk wetenschappelijk onderzoek. Het Nivel houdt zich hierbij strikt aan de AVG (Algemene Verordening Gegevensbescherming). Liever niet meedoen met de tellingen? Meld dit bij [&hellip;]","og_url":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/","og_site_name":"Huisartsenpost Drechtdokters - English","article_published_time":"2022-12-06T11:15:09+00:00","article_modified_time":"2022-12-06T11:15:11+00:00","author":"MINDD","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MINDD","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/#article","isPartOf":{"@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/"},"author":{"name":"MINDD","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206"},"headline":"Nivel zorgregistratie","datePublished":"2022-12-06T11:15:09+00:00","dateModified":"2022-12-06T11:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/"},"wordCount":59,"commentCount":0,"articleSection":["Geen onderdeel van een categorie"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/","url":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/","name":"Nivel zorgregistratie - Huisartsenpost Drechtdokters - English","isPartOf":{"@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/#website"},"datePublished":"2022-12-06T11:15:09+00:00","dateModified":"2022-12-06T11:15:11+00:00","author":{"@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206"},"breadcrumb":{"@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/2022\/12\/06\/nivel-zorgregistratie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Nivel zorgregistratie"}]},{"@type":"WebSite","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/#website","url":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/","name":"Huisartsenpost Drechtdokters - English","description":"Development site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206","name":"MINDD","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-content\/litespeed\/avatar\/74\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512","url":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-content\/litespeed\/avatar\/74\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512","contentUrl":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-content\/litespeed\/avatar\/74\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1783901512","caption":"MINDD"},"url":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/blog\/author\/mindd-beheer\/"}]}},"_links":{"self":[{"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/posts\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":0,"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"wp:attachment":[{"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huisartsenpostdrechtdokters.nl\/en\/wp-json\/wp\/v2\/categories?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}